{"id":9909,"date":"2018-10-25T08:22:03","date_gmt":"2018-10-25T07:22:03","guid":{"rendered":"http:\/\/de.newsroom.fb.com\/?p=9909"},"modified":"2018-10-25T08:22:03","modified_gmt":"2018-10-25T07:22:03","slug":"kontext-button","status":"publish","type":"post","link":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/","title":{"rendered":"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen"},"content":{"rendered":"<p><i>Von Taylor Hughes, Software Engineer, Jeff Smith, Product Designer und Alex Leavitt, UX Researcher<\/i><\/p>\n<p>Im vergangenen Jahr haben wir in den USA im Rahmen eines <a href=\"https:\/\/newsroom.fb.com\/news\/2017\/10\/news-feed-fyi-new-test-to-provide-context-about-articles\/\">Tests<\/a> damit begonnen, den Menschen mehr Hintergrundinformationen zu Nachrichtenquellen und Artikeln in ihrem News Feed zu geben. Seit dem haben wir die Funktion sukzessive ausgerollt.\u00a0Ab sofort ist der <a href=\"https:\/\/www.facebook.com\/help\/publisher\/1004556093058199\">Kontext-Button<\/a>\u00a0auch in Deutschland verf\u00fcgbar. Wir erg\u00e4nzen zudem weitere Funktionen, um den Menschen noch mehr Kontext rund um die Inhalte und Seiten auf Facebook zu bieten \u2013 sodass sie selbst entscheiden k\u00f6nnen, was sie lesen, wem sie vertrauen und was sie teilen.<\/p>\n<p>Es konnten einige zentrale Aspekte identifiziert werden, die dabei helfen k\u00f6nnen, die Glaubw\u00fcrdigkeit eines Artikels und die Vertrauensw\u00fcrdigkeit einer Quelle zu beurteilen \u2013 und zwar durch Untersuchungen mit unserer Community sowie Partnern aus Wissenschaft und Industrie. Basierend darauf schaffen wir M\u00f6glichkeiten, wie Kontext zu einem Artikel sichtbar gemacht werden kann. Dazu geh\u00f6ren folgende Punkte: der Wikipedia-Eintrag zu einer Nachrichtenquelle, \u00e4hnliche Artikel zu einem Thema, Informationen dar\u00fcber, wie oft und wo der Artikel auf Facebook geteilt wurde, sowie die M\u00f6glichkeit, der Seite der Nachrichtenquelle zu folgen. Sollte eine Nachrichtenquelle keinen Eintrag bei Wikipedia haben, so vermerken wir dies, denn auch hierbei kann es sich um relevanten Kontext handeln.<\/p>\n<p>Neben den Informationen, die bereits bei unserem ersten Test integriert wurden, erg\u00e4nzen wir nun zwei weitere Funktionen. Diese werden f\u00fcr noch mehr Kontext sorgen:<\/p>\n<ul>\n<li style=\"list-style-type:none\">\n<ul>\n<li><b>Weitere Artikel von dieser Nachrichtenquelle: <\/b>Diese Funktion gibt den Menschen einen kurzen \u00dcberblick \u00fcber weitere aktuelle Artikel der Nachrichtenquelle.<\/li>\n<li><b>Von Freunden geteilt: <\/b>Diese Funktion zeigt, ob und welche Freunde einen Artikel geteilt haben.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/10157254148271729\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<p>Mit einem weiteren Test wollen wir herausfinden, ob die Menschen die Glaubw\u00fcrdigkeit eines Artikels besser beurteilen k\u00f6nnen, wenn sie \u00fcber Informationen \u00fcber den Autor verf\u00fcgen. Menschen, die Teil dieses Tests sind, k\u00f6nnen in <a href=\"https:\/\/newsroom.fb.com\/news\/2015\/05\/instant-articles-a-faster-reading-experience-on-facebook\/\">Instant Articles<\/a> auf den Namen des Autors klicken, um zus\u00e4tzliche Informationen zu erhalten, so z.B. eine Beschreibung von dessen Wikipedia-Seite, ein Button zum Folgen der Seite bzw. des Profils sowie weitere k\u00fcrzlich von diesem Autor ver\u00f6ffentlichte Artikel. Diese Information wird jedoch nur angezeigt, wenn der Autor auf seiner Website die sogenannten <a href=\"https:\/\/media.fb.com\/2015\/06\/18\/using-author-tags-to-grow-your-audience\/\">Author Tags<\/a> implementiert hat, sodass die Seite bzw. das Profil mit der Verfasserangabe verkn\u00fcpft werden kann. Au\u00dferdem muss die Nachrichtenquelle best\u00e4tigt haben, dass eine Verbindung zwischen ihm und dem Autor besteht. Zun\u00e4chst handelt es sich hierbei um einen kleinen Test in den USA. Wir sind gespannt, welche Erkenntnisse sich daraus ergeben.<\/p>\n<p>Wir haben diese Funktionen auf Basis von Feedback und Input von unterschiedlichen Menschen und Nachrichtenquellen entwickelt, auch im Rahmen unseres Facebook Journalism Project. Es war eine echte Herausforderung, eine M\u00f6glichkeit zu schaffen, sachlichen Kontext zu den Nachrichten im News Feed hinzuzuf\u00fcgen. In unserem <a href=\"https:\/\/medium.com\/facebook-design\/designing-new-ways-to-give-context-to-news-stories-f6c13604f450\">Facebook Design Blog<\/a> haben wir den Designprozess begleitet.<\/p>\n<p>Wir arbeiten auch weiterhin kontinuierlich daran, die Nutzererfahrung zu verbessern und Menschen mehr Kontext zu den Nachrichten auf Facebook zu bieten.<\/p>\n<p><b>Update 31. Mai:<\/b> Wir beginnen heute damit, diese Funktion in den UK bereitzustellen.<\/p>\n<p><b>Update 19. September:<\/b> Wir beginnen heute damit, den Kontext-Button in Kanada, Australien, Neuseeland und Irland zur Verf\u00fcgung zu stellen.<\/p>\n<ul>\n<li style=\"list-style-type:none\">\n<ul>\n<li>Wir integrieren in den Informationen jetzt auch das Alter einer Website\/einer Domain<\/li>\n<li>Wir stellen dies jetzt nicht nur f\u00fcr Artikel zur Verf\u00fcgung, sondern auch f\u00fcr alle Links.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p><b>Update 25. Oktober: <\/b>Nach Gro\u00dfbritannien, Kanada, Australien, Neuseeland and Irland in den letzten Monaten, f\u00fchren wir heute in Deutschland, Frankreich, Spanien, Italien, Polen und Indien den Kontext-Button ein.<\/p>\n<div class=\"fb-video\" data-allowfullscreen=\"true\" data-href=\"https:\/\/www.facebook.com\/facebook\/videos\/1860469670706678\/\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n","protected":false},"excerpt":{"rendered":"Von Taylor Hughes, Software Engineer, Jeff Smith, Product Designer und Alex Leavitt, UX Researcher Im vergangenen Jahr haben wir in den USA im Rahmen eines Tests damit begonnen, den Menschen mehr Hintergrundinformationen zu Nachrichtenquellen und Artikeln in ihrem News Feed zu geben. Seit dem haben wir die Funktion sukzessive ausgerollt.\u00a0Ab sofort ist der Kontext-Button\u00a0auch in Deutschland verf\u00fcgbar. Wir erg\u00e4nzen zudem weitere Funktionen, um den Menschen noch mehr Kontext rund um die Inhalte und Seiten auf Facebook zu bieten \u2013 sodass sie selbst entscheiden k\u00f6nnen, was sie lesen, wem sie vertrauen und was sie teilen. Es konnten einige zentrale Aspekte identifiziert werden, die dabei helfen k\u00f6nnen, die Glaubw\u00fcrdigkeit eines Artikels und die Vertrauensw\u00fcrdigkeit einer Quelle zu beurteilen \u2013 und zwar durch Untersuchungen mit unserer Community sowie Partnern aus Wissenschaft und Industrie. Basierend darauf schaffen wir M\u00f6glichkeiten, wie Kontext zu einem Artikel sichtbar gemacht werden kann. Dazu geh\u00f6ren folgende Punkte: der Wikipedia-Eintrag zu einer Nachrichtenquelle, \u00e4hnliche Artikel zu einem Thema, Informationen dar\u00fcber, wie oft und wo der Artikel auf Facebook geteilt wurde, sowie die M\u00f6glichkeit, der Seite der Nachrichtenquelle zu folgen. Sollte eine Nachrichtenquelle keinen Eintrag bei Wikipedia haben, so vermerken wir dies, denn auch hierbei kann es sich um relevanten Kontext handeln. Neben den Informationen, die bereits bei unserem ersten Test integriert wurden, erg\u00e4nzen wir nun zwei weitere Funktionen. Diese werden f\u00fcr noch mehr Kontext sorgen: Weitere Artikel von dieser Nachrichtenquelle: Diese Funktion gibt den Menschen einen kurzen \u00dcberblick \u00fcber weitere aktuelle Artikel der Nachrichtenquelle. Von Freunden geteilt: Diese Funktion zeigt, ob und welche Freunde einen Artikel geteilt haben. Mit einem weiteren Test wollen wir herausfinden, ob die Menschen die Glaubw\u00fcrdigkeit eines Artikels besser beurteilen k\u00f6nnen, wenn sie \u00fcber Informationen \u00fcber den Autor verf\u00fcgen. Menschen, die Teil dieses Tests sind, k\u00f6nnen in Instant Articles auf den Namen des Autors klicken, um zus\u00e4tzliche Informationen zu erhalten, so z.B. eine Beschreibung von dessen Wikipedia-Seite, ein Button zum Folgen der Seite bzw. des Profils sowie weitere k\u00fcrzlich von diesem Autor ver\u00f6ffentlichte Artikel. Diese Information wird jedoch nur angezeigt, wenn der Autor auf seiner Website die sogenannten Author Tags implementiert hat, sodass die Seite bzw. das Profil mit der Verfasserangabe verkn\u00fcpft werden kann. Au\u00dferdem muss die Nachrichtenquelle best\u00e4tigt haben, dass eine Verbindung zwischen ihm und dem Autor besteht. Zun\u00e4chst handelt es sich hierbei um einen kleinen Test in den USA. Wir sind gespannt, welche Erkenntnisse sich daraus ergeben. Wir haben diese Funktionen auf Basis von Feedback und Input von unterschiedlichen Menschen und Nachrichtenquellen entwickelt, auch im Rahmen unseres Facebook Journalism Project. Es war eine echte Herausforderung, eine M\u00f6glichkeit zu schaffen, sachlichen Kontext zu den Nachrichten im News Feed hinzuzuf\u00fcgen. In unserem Facebook Design Blog haben wir den Designprozess begleitet. Wir arbeiten auch weiterhin kontinuierlich daran, die Nutzererfahrung zu verbessern und Menschen mehr Kontext zu den Nachrichten auf Facebook zu bieten. Update 31. Mai: Wir beginnen heute damit, diese Funktion in den UK bereitzustellen. Update 19. September: Wir beginnen heute damit, den Kontext-Button in Kanada, Australien, Neuseeland und Irland zur Verf\u00fcgung zu stellen. Wir integrieren in den Informationen jetzt auch das Alter einer Website\/einer Domain Wir stellen dies jetzt nicht nur f\u00fcr Artikel zur Verf\u00fcgung, sondern auch f\u00fcr alle Links. Update 25. Oktober: Nach Gro\u00dfbritannien, Kanada, Australien, Neuseeland and Irland in den letzten Monaten, f\u00fchren wir heute in Deutschland, Frankreich, Spanien, Italien, Polen und Indien den Kontext-Button ein.","protected":false},"author":119732082,"featured_media":9915,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[555973284,243889734],"tags":[],"class_list":["post-9909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inside-feed","category-produktnachrichten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen | \u00dcber Meta<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen | \u00dcber Meta\" \/>\n<meta property=\"og:description\" content=\"Von Taylor Hughes, Software Engineer, Jeff Smith, Product Designer und Alex Leavitt, UX Researcher Im vergangenen Jahr haben wir in den USA im Rahmen eines Tests damit begonnen, den Menschen mehr Hintergrundinformationen zu Nachrichtenquellen und Artikeln in ihrem News Feed zu geben. Seit dem haben wir die Funktion sukzessive ausgerollt.\u00a0Ab sofort ist der Kontext-Button\u00a0auch in Deutschland verf\u00fcgbar. Wir erg\u00e4nzen zudem weitere Funktionen, um den Menschen noch mehr Kontext rund um die Inhalte und Seiten auf Facebook zu bieten \u2013 sodass sie selbst entscheiden k\u00f6nnen, was sie lesen, wem sie vertrauen und was sie teilen. Es konnten einige zentrale Aspekte identifiziert werden, die dabei helfen k\u00f6nnen, die Glaubw\u00fcrdigkeit eines Artikels und die Vertrauensw\u00fcrdigkeit einer Quelle zu beurteilen \u2013 und zwar durch Untersuchungen mit unserer Community sowie Partnern aus Wissenschaft und Industrie. Basierend darauf schaffen wir M\u00f6glichkeiten, wie Kontext zu einem Artikel sichtbar gemacht werden kann. Dazu geh\u00f6ren folgende Punkte: der Wikipedia-Eintrag zu einer Nachrichtenquelle, \u00e4hnliche Artikel zu einem Thema, Informationen dar\u00fcber, wie oft und wo der Artikel auf Facebook geteilt wurde, sowie die M\u00f6glichkeit, der Seite der Nachrichtenquelle zu folgen. Sollte eine Nachrichtenquelle keinen Eintrag bei Wikipedia haben, so vermerken wir dies, denn auch hierbei kann es sich um relevanten Kontext handeln. Neben den Informationen, die bereits bei unserem ersten Test integriert wurden, erg\u00e4nzen wir nun zwei weitere Funktionen. Diese werden f\u00fcr noch mehr Kontext sorgen: Weitere Artikel von dieser Nachrichtenquelle: Diese Funktion gibt den Menschen einen kurzen \u00dcberblick \u00fcber weitere aktuelle Artikel der Nachrichtenquelle. Von Freunden geteilt: Diese Funktion zeigt, ob und welche Freunde einen Artikel geteilt haben. Mit einem weiteren Test wollen wir herausfinden, ob die Menschen die Glaubw\u00fcrdigkeit eines Artikels besser beurteilen k\u00f6nnen, wenn sie \u00fcber Informationen \u00fcber den Autor verf\u00fcgen. Menschen, die Teil dieses Tests sind, k\u00f6nnen in Instant Articles auf den Namen des Autors klicken, um zus\u00e4tzliche Informationen zu erhalten, so z.B. eine Beschreibung von dessen Wikipedia-Seite, ein Button zum Folgen der Seite bzw. des Profils sowie weitere k\u00fcrzlich von diesem Autor ver\u00f6ffentlichte Artikel. Diese Information wird jedoch nur angezeigt, wenn der Autor auf seiner Website die sogenannten Author Tags implementiert hat, sodass die Seite bzw. das Profil mit der Verfasserangabe verkn\u00fcpft werden kann. Au\u00dferdem muss die Nachrichtenquelle best\u00e4tigt haben, dass eine Verbindung zwischen ihm und dem Autor besteht. Zun\u00e4chst handelt es sich hierbei um einen kleinen Test in den USA. Wir sind gespannt, welche Erkenntnisse sich daraus ergeben. Wir haben diese Funktionen auf Basis von Feedback und Input von unterschiedlichen Menschen und Nachrichtenquellen entwickelt, auch im Rahmen unseres Facebook Journalism Project. Es war eine echte Herausforderung, eine M\u00f6glichkeit zu schaffen, sachlichen Kontext zu den Nachrichten im News Feed hinzuzuf\u00fcgen. In unserem Facebook Design Blog haben wir den Designprozess begleitet. Wir arbeiten auch weiterhin kontinuierlich daran, die Nutzererfahrung zu verbessern und Menschen mehr Kontext zu den Nachrichten auf Facebook zu bieten. Update 31. Mai: Wir beginnen heute damit, diese Funktion in den UK bereitzustellen. Update 19. September: Wir beginnen heute damit, den Kontext-Button in Kanada, Australien, Neuseeland und Irland zur Verf\u00fcgung zu stellen. Wir integrieren in den Informationen jetzt auch das Alter einer Website\/einer Domain Wir stellen dies jetzt nicht nur f\u00fcr Artikel zur Verf\u00fcgung, sondern auch f\u00fcr alle Links. Update 25. Oktober: Nach Gro\u00dfbritannien, Kanada, Australien, Neuseeland and Irland in den letzten Monaten, f\u00fchren wir heute in Deutschland, Frankreich, Spanien, Italien, Polen und Indien den Kontext-Button ein.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcber Meta\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-25T07:22:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?resize=1024,683\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"apcoworldwide\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Meta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\"},\"author\":\"Facebook company\",\"headline\":\"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen\",\"datePublished\":\"2018-10-25T07:22:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\"},\"wordCount\":610,\"publisher\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200\",\"articleSection\":[\"Inside Feed\",\"Produktnachrichten\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\",\"url\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\",\"name\":\"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen | \u00dcber Meta\",\"isPartOf\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200\",\"datePublished\":\"2018-10-25T07:22:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/\"]}],\"author\":\"\u00dcber Meta\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage\",\"url\":\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200\",\"contentUrl\":\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200\",\"width\":1800,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/about-fb-develop.go-vip.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#website\",\"url\":\"https:\/\/about.fb.com\/news\/\",\"name\":\"\u00dcber Meta\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/about-fb-develop.go-vip.net\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\",\"alternateName\":[\"Meta Newsroom\",\"Meta\"]},{\"@type\":\"Organization\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#organization\",\"name\":\"Meta\",\"url\":\"https:\/\/about-fb-develop.go-vip.net\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"contentUrl\":\"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500\",\"width\":8000,\"height\":4500,\"caption\":\"Meta\"},\"image\":{\"@id\":\"https:\/\/about-fb-develop.go-vip.net\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen | \u00dcber Meta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/","og_locale":"de_DE","og_type":"article","og_title":"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen | \u00dcber Meta","og_description":"Von Taylor Hughes, Software Engineer, Jeff Smith, Product Designer und Alex Leavitt, UX Researcher Im vergangenen Jahr haben wir in den USA im Rahmen eines Tests damit begonnen, den Menschen mehr Hintergrundinformationen zu Nachrichtenquellen und Artikeln in ihrem News Feed zu geben. Seit dem haben wir die Funktion sukzessive ausgerollt.\u00a0Ab sofort ist der Kontext-Button\u00a0auch in Deutschland verf\u00fcgbar. Wir erg\u00e4nzen zudem weitere Funktionen, um den Menschen noch mehr Kontext rund um die Inhalte und Seiten auf Facebook zu bieten \u2013 sodass sie selbst entscheiden k\u00f6nnen, was sie lesen, wem sie vertrauen und was sie teilen. Es konnten einige zentrale Aspekte identifiziert werden, die dabei helfen k\u00f6nnen, die Glaubw\u00fcrdigkeit eines Artikels und die Vertrauensw\u00fcrdigkeit einer Quelle zu beurteilen \u2013 und zwar durch Untersuchungen mit unserer Community sowie Partnern aus Wissenschaft und Industrie. Basierend darauf schaffen wir M\u00f6glichkeiten, wie Kontext zu einem Artikel sichtbar gemacht werden kann. Dazu geh\u00f6ren folgende Punkte: der Wikipedia-Eintrag zu einer Nachrichtenquelle, \u00e4hnliche Artikel zu einem Thema, Informationen dar\u00fcber, wie oft und wo der Artikel auf Facebook geteilt wurde, sowie die M\u00f6glichkeit, der Seite der Nachrichtenquelle zu folgen. Sollte eine Nachrichtenquelle keinen Eintrag bei Wikipedia haben, so vermerken wir dies, denn auch hierbei kann es sich um relevanten Kontext handeln. Neben den Informationen, die bereits bei unserem ersten Test integriert wurden, erg\u00e4nzen wir nun zwei weitere Funktionen. Diese werden f\u00fcr noch mehr Kontext sorgen: Weitere Artikel von dieser Nachrichtenquelle: Diese Funktion gibt den Menschen einen kurzen \u00dcberblick \u00fcber weitere aktuelle Artikel der Nachrichtenquelle. Von Freunden geteilt: Diese Funktion zeigt, ob und welche Freunde einen Artikel geteilt haben. Mit einem weiteren Test wollen wir herausfinden, ob die Menschen die Glaubw\u00fcrdigkeit eines Artikels besser beurteilen k\u00f6nnen, wenn sie \u00fcber Informationen \u00fcber den Autor verf\u00fcgen. Menschen, die Teil dieses Tests sind, k\u00f6nnen in Instant Articles auf den Namen des Autors klicken, um zus\u00e4tzliche Informationen zu erhalten, so z.B. eine Beschreibung von dessen Wikipedia-Seite, ein Button zum Folgen der Seite bzw. des Profils sowie weitere k\u00fcrzlich von diesem Autor ver\u00f6ffentlichte Artikel. Diese Information wird jedoch nur angezeigt, wenn der Autor auf seiner Website die sogenannten Author Tags implementiert hat, sodass die Seite bzw. das Profil mit der Verfasserangabe verkn\u00fcpft werden kann. Au\u00dferdem muss die Nachrichtenquelle best\u00e4tigt haben, dass eine Verbindung zwischen ihm und dem Autor besteht. Zun\u00e4chst handelt es sich hierbei um einen kleinen Test in den USA. Wir sind gespannt, welche Erkenntnisse sich daraus ergeben. Wir haben diese Funktionen auf Basis von Feedback und Input von unterschiedlichen Menschen und Nachrichtenquellen entwickelt, auch im Rahmen unseres Facebook Journalism Project. Es war eine echte Herausforderung, eine M\u00f6glichkeit zu schaffen, sachlichen Kontext zu den Nachrichten im News Feed hinzuzuf\u00fcgen. In unserem Facebook Design Blog haben wir den Designprozess begleitet. Wir arbeiten auch weiterhin kontinuierlich daran, die Nutzererfahrung zu verbessern und Menschen mehr Kontext zu den Nachrichten auf Facebook zu bieten. Update 31. Mai: Wir beginnen heute damit, diese Funktion in den UK bereitzustellen. Update 19. September: Wir beginnen heute damit, den Kontext-Button in Kanada, Australien, Neuseeland und Irland zur Verf\u00fcgung zu stellen. Wir integrieren in den Informationen jetzt auch das Alter einer Website\/einer Domain Wir stellen dies jetzt nicht nur f\u00fcr Artikel zur Verf\u00fcgung, sondern auch f\u00fcr alle Links. Update 25. Oktober: Nach Gro\u00dfbritannien, Kanada, Australien, Neuseeland and Irland in den letzten Monaten, f\u00fchren wir heute in Deutschland, Frankreich, Spanien, Italien, Polen und Indien den Kontext-Button ein.","og_url":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/","og_site_name":"\u00dcber Meta","article_published_time":"2018-10-25T07:22:03+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?resize=1024,683","type":"image\/png"}],"author":"apcoworldwide","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Meta","Est. reading time":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#article","isPartOf":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/"},"author":"Facebook company","headline":"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen","datePublished":"2018-10-25T07:22:03+00:00","mainEntityOfPage":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/"},"wordCount":610,"publisher":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#organization"},"image":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage"},"thumbnailUrl":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200","articleSection":["Inside Feed","Produktnachrichten"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/","url":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/","name":"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen | \u00dcber Meta","isPartOf":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage"},"image":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage"},"thumbnailUrl":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200","datePublished":"2018-10-25T07:22:03+00:00","breadcrumb":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/"]}],"author":"\u00dcber Meta"},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#primaryimage","url":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200","contentUrl":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200","width":1800,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/news\/2018\/10\/kontext-button\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/about-fb-develop.go-vip.net\/de\/"},{"@type":"ListItem","position":2,"name":"Kontext-Button: So helfen wir Menschen, Nachrichten im News Feed und deren Ursprung noch besser einzusch\u00e4tzen"}]},{"@type":"WebSite","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#website","url":"https:\/\/about.fb.com\/news\/","name":"\u00dcber Meta","description":"","publisher":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/about-fb-develop.go-vip.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE","alternateName":["Meta Newsroom","Meta"]},{"@type":"Organization","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#organization","name":"Meta","url":"https:\/\/about-fb-develop.go-vip.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","contentUrl":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2021\/10\/meta-social-16x9-1.jpg?fit=8000%2C4500","width":8000,"height":4500,"caption":"Meta"},"image":{"@id":"https:\/\/about-fb-develop.go-vip.net\/de\/#\/schema\/logo\/image\/"}}]}},"jetpack_featured_media_url":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-content\/uploads\/sites\/10\/2018\/10\/kontext-button.png?fit=1800%2C1200","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/posts\/9909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/users\/119732082"}],"replies":[{"embeddable":true,"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/comments?post=9909"}],"version-history":[{"count":0,"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/posts\/9909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/media\/9915"}],"wp:attachment":[{"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/media?parent=9909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/categories?post=9909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/about-fb-develop.go-vip.net\/de\/wp-json\/wp\/v2\/tags?post=9909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}